{"id":3637,"date":"2024-05-04T18:19:41","date_gmt":"2024-05-04T21:19:41","guid":{"rendered":"http:\/\/www.produccioneseg.com.ar\/eg\/?p=3637"},"modified":"2024-10-25T09:59:57","modified_gmt":"2024-10-25T12:59:57","slug":"mariana-gomez-badia-en-tandil","status":"publish","type":"post","link":"https:\/\/www.produccioneseg.com.ar\/eg\/mariana-gomez-badia-en-tandil\/","title":{"rendered":"MARIANA GOMEZ BADIA EN TANDIL"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>La presentaci\u00f3n que que estaba planeada para el S\u00e1bado 6 se reprogramara, en breve estaremos anunciando la fecha.<\/strong><\/p>\n\n\n\n<p>El s\u00e1bado 6 de julio a las 20.30hs se presenta en el Centro Cultural Universitario Mariana Gomez Badia con \u00abManifesta tu Poder y Transforma tu Vida\u00bb  <\/p>\n\n\n\n<p>Todos llevamos dentro una esencia que necesita ser mirada, explorada y expandida pero muchas veces nos quedamos (conscientes o no) enredados en el pasado o en la mirada limitante de la familia y as\u00ed, el maestro que nos habita, permanece dormido para cumplir con el \u00abdeber ser\u00bb.<br>Es muy f\u00e1cil caer en la resignaci\u00f3n y en el abandono de los sue\u00f1os, pero tu alma ya siente que es momento de despertar, dar el salto y SER.<br>Te invito a conocer las implicancias sist\u00e9micas y los talentos que viven en vos. Te invito a mirar m\u00e1s all\u00e1 de los relatos, Te invito a conectar con el poder que ya te habita: la recompensa ser\u00e1 enorme.<\/p>\n\n\n\n<p>Entradas en venta en&nbsp;<a href=\"https:\/\/www.instagram.com\/pluscolortandil\/?hl=es-la\">@pluscolortandil<\/a>&nbsp;&#8230; Compr\u00e1 t\u00fa entrada con&nbsp;<a href=\"https:\/\/www.instagram.com\/tarjeta.elebar\/?hl=es-la\">@tarjeta.elebar<\/a>&nbsp;en 3 cuotas sin inter\u00e9s y 25% de descuento..<br>Entradas online en <a href=\"https:\/\/www.aportickets.com\/espectaculo\/APORTICKETS\/75\/mariana-gomez-badia-en-tandil.html\">Aportickets.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presentaci\u00f3n que que estaba planeada para el S\u00e1bado 6 se reprogramara, en breve estaremos anunciando la fecha. El s\u00e1bado 6 de julio a las 20.30hs se presenta en el Centro Cultural Universitario Mariana Gomez Badia con \u00abManifesta tu Poder y Transforma tu Vida\u00bb Todos llevamos dentro una esencia que necesita ser mirada, explorada y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-3637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anteriores-de-2024"],"_links":{"self":[{"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/posts\/3637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/comments?post=3637"}],"version-history":[{"count":4,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/posts\/3637\/revisions"}],"predecessor-version":[{"id":3646,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/posts\/3637\/revisions\/3646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/media\/3644"}],"wp:attachment":[{"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/media?parent=3637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/categories?post=3637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.produccioneseg.com.ar\/eg\/wp-json\/wp\/v2\/tags?post=3637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}